{"id":57,"date":"2023-05-24T18:25:25","date_gmt":"2023-05-24T18:25:25","guid":{"rendered":"https:\/\/reyamelescritor.com\/?p=57"},"modified":"2023-06-05T01:00:30","modified_gmt":"2023-06-05T01:00:30","slug":"te-amare","status":"publish","type":"post","link":"https:\/\/reyamelescritor.com\/index.php\/2023\/05\/24\/te-amare\/","title":{"rendered":"Te amar\u00e9"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><em>Te amar\u00e9 noche con noche <\/em><br><em>y en silencio en el d\u00eda<br>te amar\u00e9 como esa tarde <\/em><br><em>como un sue\u00f1o que viv\u00eda.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Te amar\u00e9 y en la distancia <\/em><br><em>mi voz te ser\u00e1 poes\u00eda <\/em><br><em>que te recuerde a diario <\/em><br><em>llen\u00e1ndome de alegr\u00eda.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Llevar\u00e9 en cada mano <\/em><br><em>muchos sue\u00f1os a t\u00fa lado <\/em><br><em>te entregar\u00e9 uno a uno <\/em><br><em>como caricias y abrazos.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Se interrumpe la distancia <\/em><br><em>al recordar solo un beso <\/em><br><em>depositado en tu cuello <\/em><br><em>depositado en silencio.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Hoy estar\u00e1s tal vez lejos <\/em><br><em>pero fundida conmigo <\/em><br><em>no importa cuan largo sea <\/em><br><em>o tan oscuro el camino.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Te amar\u00e9 y entre las sombras <\/em><br><em>estar\u00e9 tal vez dormido<br>y no querr\u00e9 despertar <\/em><br><em>hasta que vuelvas conmigo.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Es la distancia que envuelve <\/em><br><em>a todo aquel peregrino <\/em><br><em>que se marcha de sus sue\u00f1os <\/em><br><em>y se pierde en el camino.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Pero aqu\u00ed tendr\u00e1s mis brazos <\/em><br><em>abiertos a t\u00fa regreso <\/em><br><em>que te esperan sedientos <\/em><br><em>con mil caricias y besos.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El amor verdadero se desea, se busca y cuando se encuentra se conserva para siempre, cuid\u00e1ndolo, cultiv\u00e1ndolo y regresando con esos peque\u00f1os detalles como el cari\u00f1o, palabras hermosas y sobre todo amor en cada una de nuestras acciones para quienes amamos.<\/p>\n","protected":false},"author":2,"featured_media":58,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[20],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/reyamelescritor.com\/index.php\/wp-json\/wp\/v2\/posts\/57"}],"collection":[{"href":"https:\/\/reyamelescritor.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reyamelescritor.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reyamelescritor.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reyamelescritor.com\/index.php\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":2,"href":"https:\/\/reyamelescritor.com\/index.php\/wp-json\/wp\/v2\/posts\/57\/revisions"}],"predecessor-version":[{"id":116,"href":"https:\/\/reyamelescritor.com\/index.php\/wp-json\/wp\/v2\/posts\/57\/revisions\/116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reyamelescritor.com\/index.php\/wp-json\/wp\/v2\/media\/58"}],"wp:attachment":[{"href":"https:\/\/reyamelescritor.com\/index.php\/wp-json\/wp\/v2\/media?parent=57"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reyamelescritor.com\/index.php\/wp-json\/wp\/v2\/categories?post=57"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reyamelescritor.com\/index.php\/wp-json\/wp\/v2\/tags?post=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}